{"id":1117,"date":"2026-02-19T08:47:04","date_gmt":"2026-02-19T14:47:04","guid":{"rendered":"https:\/\/facmedicalblog.com\/?post_type=product&#038;p=1117"},"modified":"2026-03-30T17:15:18","modified_gmt":"2026-03-30T23:15:18","slug":"motor-de-implantes-dentales-motorsurg","status":"publish","type":"product","link":"https:\/\/facmedicalblog.com\/index.php\/producto\/motor-de-implantes-dentales-motorsurg\/","title":{"rendered":"Motor de Implantes Dentales MotorSurg"},"content":{"rendered":"<p><strong>Motor de Implantes Dentales MotorSurg<\/strong><\/p>\n<ul>\n<li>Potencia y precisi\u00f3n: Proporciona la potencia necesaria para insertar implantes dentales con precisi\u00f3n en hueso maxilar o mandibular, asegurando un procedimiento seguro.<\/li>\n<li>Ajuste de velocidad: Permite ajustar la velocidad de rotaci\u00f3n seg\u00fan las necesidades del procedimiento y la densidad del hueso, compatible con una amplia gama de implantes.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Motor de Implantes Dentales MotorSurg Potencia y precisi\u00f3n: Proporciona la potencia necesaria para insertar implantes dentales con precisi\u00f3n en hueso maxilar o mandibular, asegurando un procedimiento seguro. Ajuste de velocidad: Permite ajustar la velocidad de rotaci\u00f3n seg\u00fan las necesidades del procedimiento y la densidad del hueso, compatible con una amplia gama de implantes.<\/p>\n","protected":false},"featured_media":1118,"comment_status":"open","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[404],"product_tag":[],"class_list":{"0":"post-1117","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-motores-implantes","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple","12":"add-to-wishlist-before_image"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/facmedicalblog.com\/index.php\/wp-json\/wp\/v2\/product\/1117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/facmedicalblog.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/facmedicalblog.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/facmedicalblog.com\/index.php\/wp-json\/wp\/v2\/comments?post=1117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/facmedicalblog.com\/index.php\/wp-json\/wp\/v2\/media\/1118"}],"wp:attachment":[{"href":"https:\/\/facmedicalblog.com\/index.php\/wp-json\/wp\/v2\/media?parent=1117"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/facmedicalblog.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=1117"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/facmedicalblog.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=1117"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/facmedicalblog.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=1117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}